{"id":32345,"date":"2021-11-05T09:42:20","date_gmt":"2021-11-05T08:42:20","guid":{"rendered":"https:\/\/www.studiochiesa.it\/?p=32345"},"modified":"2024-07-22T11:24:16","modified_gmt":"2024-07-22T09:24:16","slug":"dal-g20-lappello-a-sostenere-le-pmi-del-mondo","status":"publish","type":"post","link":"https:\/\/www.studiochiesa.it\/en\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/","title":{"rendered":"Dal G20 l&#8217;appello a sostenere le PMI del mondo"},"content":{"rendered":"<p>I dati recenti del\u00a02021 stanno testimoniando\u00a0una forte crescita di\u00a0tutte le PMI europee e in particolare delle italiane che operano in\u00a0Lombardia (+5,2%), Emilia-Romagna (+5,8%),\u00a0Veneto (+5,8%): le PMI si confermano sempre pi\u00f9 il cuore pulsante dell\u2019economia.<br \/>\nIn Italia, solo le PMI lombarde, emiliano-romagnole e venete\u00a0rappresentano insieme il\u00a041% del PIL\u00a0italiano.<br \/>\nUn sistema che vale il\u00a054% dell\u2019export nazionale, il\u00a037% dell\u2019occupazione, il\u00a032% delle imprese.<\/p>\n<p>A livello globale le PMI contribuiscono a oltre la met\u00e0 dell\u2019occupazione mondiale. Tuttavia, circa la met\u00e0 di esse, ha ancora un accesso molto limitato al credito: da ci\u00f2 deriva anche la difficolt\u00e0 ad affacciarsi ai nuovi mercati.<\/p>\n<p>Questo \u00e8 stato sottolineato anche nel corso dell\u2019ultimo Summit G20 dal discorso della\u00a0Regina Maxima\u00a0dei Paesi Bassi, speaker d\u2019eccezione, in veste di avvocato speciale del segretario generale della Nazioni Unite per il finanziamento inclusivo per lo sviluppo.<br \/>\n\u201cRiconosciamo tutti l\u2019enorme contributo che le PMI danno alle nostre societ\u00e0 ed economie, fornendo un reddito a milioni di famiglie. Dipendiamo da loro per una crescita pi\u00f9 equa e sostenibile. Loro sono anche i principali motori dell\u2019innovazione\u201d, ha affermato Sua Eccellenza, chiedendo un sostegno, perch\u00e9 \u00e8 anche attraverso le PMI che \u00e8 possibile\u00a0prevenire povert\u00e0 e disuguaglianze oltre a rafforzare la sostenibilit\u00e0.<\/p>\n<p>Il sostegno deve passare da tre leve:<\/p>\n<p><strong>#digitalizzazione<\/strong><br \/>\nNel mondo le PMI sono in ritardo nell\u2019adozione delle tecnologie digitali.\u00a0Ci\u00f2 si traduce nella perdita di opportunit\u00e0. La digitalizzazione deve fungere da leva di crescita in quanto rende le imprese pi\u00f9 efficienti e consente di aprire a nuovi mercati.<br \/>\nIn Italia, secondo una recente ricerca effettuata dalla societ\u00e0 GoDaddy che fornisce servizi digitali, la pandemia sta gi\u00e0 notevolmente accelerando l\u2019adozione di strumenti e servizi digitali da parte delle PMI, spingendo le aziende a utilizzare nuovi strumenti e piattaforme, indispensabili per crescere e realizzare nuove opportunit\u00e0 di business.<\/p>\n<p><strong>#investimento in competenze e capacit\u00e0<\/strong><br \/>\nPer adattarsi a un mondo del lavoro sempre in evoluzione, \u00e8 necessario che le PMI procedano nell\u2019investire nello sviluppo permanente dei loro collaboratori, per far\u00a0incontrare al meglio domanda e offerta sul mercato del lavoro,<br \/>\npoich\u00e9 \u201ctutti hanno bisogno di svilupparsi e imparare continuamente\u201d.<\/p>\n<p><strong>#accesso ai finanziamenti<\/strong><br \/>\nAspetto fondamentale di sviluppo \u00e8 anche la necessit\u00e0 di supporto nell\u2019accesso al credito, che si pu\u00f2 avere soltanto implementando\u00a0l\u2019intero \u201cecosistema finanziario\u201d,<br \/>\nsoprattutto\u00a0per le start-up e per le imprese con grandi prospettive di crescita.<\/p>\n<p>La\u00a0crescita globale necessita sempre pi\u00f9 di\u00a0PMI \u201cresilienti e produttive\u201d per sostenere le sfide del futuro, dunque \u00e8 necessario sostenerle, in quanto\u00a0sono essenziali\u00a0protagonisti\u00a0per una crescita inclusiva, equa e sostenibile.<\/p>","protected":false},"excerpt":{"rendered":"<p>I dati recenti del\u00a02021 stanno testimoniando\u00a0una forte crescita di\u00a0tutte le PMI europee e in particolare&#8230;<\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[137],"tags":[223],"class_list":["post-32345","post","type-post","status-publish","format-standard","hentry","category-digital-marketing","tag-223"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dal G20 l&#039;appello a sostenere le PMI del mondo - Studio Chiesa<\/title>\n<meta name=\"description\" content=\"Dal G20, l&#039;appello a sostenere le PMI mondiali per la ripresa economica. Scopri come Studio Chiesa supporta le piccole e medie imprese.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.studiochiesa.it\/en\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal G20 l&#039;appello a sostenere le PMI del mondo\" \/>\n<meta property=\"og:description\" content=\"Dal G20, l&#039;appello a sostenere le PMI mondiali per la ripresa economica. Scopri come Studio Chiesa supporta le piccole e medie imprese.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.studiochiesa.it\/en\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Studio Chiesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Studio-Chiesa\/407194632625821\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T08:42:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T09:24:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2021\/11\/2021_11_05_G20PMI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristiano Tagliabue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristiano Tagliabue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/\"},\"author\":{\"name\":\"Cristiano Tagliabue\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#\\\/schema\\\/person\\\/78fb53d354e92e9a310b4d0d2ce94361\"},\"headline\":\"Dal G20 l&#8217;appello a sostenere le PMI del mondo\",\"datePublished\":\"2021-11-05T08:42:20+00:00\",\"dateModified\":\"2024-07-22T09:24:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/\"},\"wordCount\":431,\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#organization\"},\"keywords\":[\"2023\"],\"articleSection\":[\"Digital Marketing\"],\"inLanguage\":\"en-GB\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/\",\"name\":\"Dal G20 l'appello a sostenere le PMI del mondo - Studio Chiesa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#website\"},\"datePublished\":\"2021-11-05T08:42:20+00:00\",\"dateModified\":\"2024-07-22T09:24:16+00:00\",\"description\":\"Dal G20, l'appello a sostenere le PMI mondiali per la ripresa economica. Scopri come Studio Chiesa supporta le piccole e medie imprese.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.studiochiesa.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal G20 l&#8217;appello a sostenere le PMI del mondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/\",\"name\":\"Studio Chiesa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#organization\",\"name\":\"Studio Chiesa Communication\",\"alternateName\":\"Studio Chiesa\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Studio-Chiesa\\\/407194632625821\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/studio-chiesa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/studiochiesa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/StudioChiesa\"],\"address\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/#local-main-place-address\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"45.450479\",\"longitude\":\"9.1723044\"},\"telephone\":[\"+39 0254116738\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"vatID\":\"01687340206\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#\\\/schema\\\/person\\\/78fb53d354e92e9a310b4d0d2ce94361\",\"name\":\"Cristiano Tagliabue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2b5cc4a676b8ba14a948377e20fa4b0167675cf3d699c29fe7feb5315523439?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2b5cc4a676b8ba14a948377e20fa4b0167675cf3d699c29fe7feb5315523439?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2b5cc4a676b8ba14a948377e20fa4b0167675cf3d699c29fe7feb5315523439?s=96&d=mm&r=g\",\"caption\":\"Cristiano Tagliabue\"},\"description\":\"Laureato in Giurisprudenza e professionista nel campo della comunicazione aziendale, ha collaborato sia con aziende italiane, sia in contesti internazionali come Marketing e Communication Manager. Appassionato di mercati, scenari economici, trend \u00e8 un fervido supporter della trasformazione degli atomi in bit.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/cristianotagliabuemilano\\\/\"],\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/author\\\/cristiano\\\/\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/#local-main-place-address\",\"streetAddress\":\"Piazza Arcole, 4\",\"addressLocality\":\"Milano\",\"postalCode\":\"20143\",\"addressRegion\":\"Italia\",\"addressCountry\":\"IT\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/quadratino_SC.jpg\",\"contentUrl\":\"https:\\\/\\\/www.studiochiesa.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/quadratino_SC.jpg\",\"width\":696,\"height\":696,\"caption\":\"Studio Chiesa Communication\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Milano\" \/>\n<meta name=\"geo.position\" content=\"45.450479;9.1723044\" \/>\n<meta name=\"geo.region\" content=\"Italy\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dal G20 l'appello a sostenere le PMI del mondo - Studio Chiesa","description":"Dal G20, l'appello a sostenere le PMI mondiali per la ripresa economica. Scopri come Studio Chiesa supporta le piccole e medie imprese.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.studiochiesa.it\/en\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/","og_locale":"en_GB","og_type":"article","og_title":"Dal G20 l'appello a sostenere le PMI del mondo","og_description":"Dal G20, l'appello a sostenere le PMI mondiali per la ripresa economica. Scopri come Studio Chiesa supporta le piccole e medie imprese.","og_url":"https:\/\/www.studiochiesa.it\/en\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/","og_site_name":"Studio Chiesa","article_publisher":"https:\/\/www.facebook.com\/pages\/Studio-Chiesa\/407194632625821","article_published_time":"2021-11-05T08:42:20+00:00","article_modified_time":"2024-07-22T09:24:16+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2021\/11\/2021_11_05_G20PMI.jpg","type":"image\/jpeg"}],"author":"Cristiano Tagliabue","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Cristiano Tagliabue","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/#article","isPartOf":{"@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/"},"author":{"name":"Cristiano Tagliabue","@id":"https:\/\/www.studiochiesa.it\/en\/#\/schema\/person\/78fb53d354e92e9a310b4d0d2ce94361"},"headline":"Dal G20 l&#8217;appello a sostenere le PMI del mondo","datePublished":"2021-11-05T08:42:20+00:00","dateModified":"2024-07-22T09:24:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/"},"wordCount":431,"publisher":{"@id":"https:\/\/www.studiochiesa.it\/en\/#organization"},"keywords":["2023"],"articleSection":["Digital Marketing"],"inLanguage":"en-GB","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.studiochiesa.it\/en\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/","url":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/","name":"Dal G20 l'appello a sostenere le PMI del mondo - Studio Chiesa","isPartOf":{"@id":"https:\/\/www.studiochiesa.it\/en\/#website"},"datePublished":"2021-11-05T08:42:20+00:00","dateModified":"2024-07-22T09:24:16+00:00","description":"Dal G20, l'appello a sostenere le PMI mondiali per la ripresa economica. Scopri come Studio Chiesa supporta le piccole e medie imprese.","breadcrumb":{"@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.studiochiesa.it\/"},{"@type":"ListItem","position":2,"name":"Dal G20 l&#8217;appello a sostenere le PMI del mondo"}]},{"@type":"WebSite","@id":"https:\/\/www.studiochiesa.it\/en\/#website","url":"https:\/\/www.studiochiesa.it\/en\/","name":"Studio Chiesa","description":"","publisher":{"@id":"https:\/\/www.studiochiesa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.studiochiesa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Organization","Place"],"@id":"https:\/\/www.studiochiesa.it\/en\/#organization","name":"Studio Chiesa Communication","alternateName":"Studio Chiesa","url":"https:\/\/www.studiochiesa.it\/en\/","logo":{"@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/pages\/Studio-Chiesa\/407194632625821","https:\/\/www.linkedin.com\/company\/studio-chiesa\/","https:\/\/www.instagram.com\/studiochiesa\/","https:\/\/www.youtube.com\/user\/StudioChiesa"],"address":{"@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/#local-main-place-address"},"geo":{"@type":"GeoCoordinates","latitude":"45.450479","longitude":"9.1723044"},"telephone":["+39 0254116738"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"vatID":"01687340206"},{"@type":"Person","@id":"https:\/\/www.studiochiesa.it\/en\/#\/schema\/person\/78fb53d354e92e9a310b4d0d2ce94361","name":"Cristiano Tagliabue","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/f2b5cc4a676b8ba14a948377e20fa4b0167675cf3d699c29fe7feb5315523439?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f2b5cc4a676b8ba14a948377e20fa4b0167675cf3d699c29fe7feb5315523439?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2b5cc4a676b8ba14a948377e20fa4b0167675cf3d699c29fe7feb5315523439?s=96&d=mm&r=g","caption":"Cristiano Tagliabue"},"description":"Laureato in Giurisprudenza e professionista nel campo della comunicazione aziendale, ha collaborato sia con aziende italiane, sia in contesti internazionali come Marketing e Communication Manager. Appassionato di mercati, scenari economici, trend \u00e8 un fervido supporter della trasformazione degli atomi in bit.","sameAs":["https:\/\/www.linkedin.com\/in\/cristianotagliabuemilano\/"],"url":"https:\/\/www.studiochiesa.it\/en\/author\/cristiano\/"},{"@type":"PostalAddress","@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/#local-main-place-address","streetAddress":"Piazza Arcole, 4","addressLocality":"Milano","postalCode":"20143","addressRegion":"Italia","addressCountry":"IT"},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.studiochiesa.it\/dal-g20-lappello-a-sostenere-le-pmi-del-mondo\/#local-main-organization-logo","url":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2023\/05\/quadratino_SC.jpg","contentUrl":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2023\/05\/quadratino_SC.jpg","width":696,"height":696,"caption":"Studio Chiesa Communication"}]},"geo.placename":"Milano","geo.position":{"lat":"45.450479","long":"9.1723044"},"geo.region":"Italy"},"_links":{"self":[{"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/posts\/32345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/comments?post=32345"}],"version-history":[{"count":4,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/posts\/32345\/revisions"}],"predecessor-version":[{"id":32367,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/posts\/32345\/revisions\/32367"}],"wp:attachment":[{"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/media?parent=32345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/categories?post=32345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/tags?post=32345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}