{"id":41908,"date":"2024-03-19T10:00:57","date_gmt":"2024-03-19T09:00:57","guid":{"rendered":"https:\/\/www.studiochiesa.it\/?p=41908"},"modified":"2025-03-25T15:43:21","modified_gmt":"2025-03-25T14:43:21","slug":"ritratto-friulano","status":"publish","type":"post","link":"https:\/\/www.studiochiesa.it\/en\/ritratto-friulano\/","title":{"rendered":"Ritratto Friulano"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"41908\" class=\"elementor elementor-41908\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-659b97c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"659b97c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41cc4fb\" data-id=\"41cc4fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c421d5 elementor-widget elementor-widget-text-editor\" data-id=\"8c421d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Heritage al femminile: Workout magazine incontra Alessandra Sangoi di Sangoi Spa<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deccca2 elementor-widget elementor-widget-text-editor\" data-id=\"deccca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ci sono frasi nel dire comune che sono specchio stucchevole e, diciamolo, ormai insopportabile, di stereotipi di genere: per esempio certi luoghi comuni allusivi e denigratori delle capacit\u00e0 delle donne in campo lavorativo oppure delle loro abilit\u00e0, per non parlare di quelli che, al contrario, legano l\u2019affermazione femminile nei campi pi\u00f9 vari alla seduttivit\u00e0 o alla bellezza. Uno dei pi\u00f9 noti, e purtroppo, citati recita: \u00abDietro a ogni grande uomo c\u2019\u00e8 sempre una grande donna\u00bb. Viene attribuita a Virginia Woolf, e certo si fa una certa fatica ad associarlo alla statura morale e intellettuale della grande scrittrice britannica: una persona dolorosamente libera, profondamente consapevole dell\u2019arretratezza della visione che la societ\u00e0 del suo tempo aveva delle donne, una militante suffragista che si batteva per la parit\u00e0 dei sessi, un\u2019ardente fautrice della necessit\u00e0 che ogni donna potesse avere una \u00abstanza tutta per s\u00e9\u00bb oltre che \u00abuna rendita di cinquecento sterline l\u2019anno\u00bb per essere indipendente ed esprimere se stessa. Quella sua presunta frase non le rende granch\u00e9 giustizia: risuona sorda come una campana crepata, appare come un \u00abcontentino\u00bb, una sorta di premio di consolazione per quelle donne che hanno fatto un passo indietro, che hanno vissuto nel cono d\u2019ombra dei loro compagni di vita rendendosi invisibili pur svolgendo compiti fondamentali per l\u2019affermazione dei partner. Sarebbe diverso se si facesse invece riferimento al detto latino al quale (sembra) che la Woolf si sia ispirata e cio\u00e8: \u00ab<em>Dotata animi mulier virum regit<\/em>\u00bb (Una donna dotata di coraggio sostiene e consiglia il marito)? Non del tutto, ma almeno si renderebbe parzialmente giustizia al peso che le donne hanno all\u2019interno della coppia, ancora di pi\u00f9 se questa coppia lo \u00e8 anche nel lavoro.<\/p>\n<p>Lidia Pino camminava a fianco del marito, non dietro. Moglie di Gino Sangoi, fonda con lui nel 1973 l\u2019impresa che oggi \u00e8 diventata un <strong>Gruppo di cinque societ\u00e0<\/strong>, con una capogruppo (SAFIN SPA) da cui dipendono quattro realt\u00e0 che operano tutte nella filiera dell\u2019acciaio: SANGOI SPA e SIDECO SRL (centri servizi per la fornitura di nastri e lamiere in acciaio), SABREST SRL (produzione di componenti di precisione) e SANGOI GREEN SRL (pali e accessori da vigna). \u00abMia madre non ha mai voluto svolgere un ruolo operativo all\u2019interno dell\u2019azienda \u2013 ci racconta <strong>Alessandra Sangoi, CEO di SANGOI SPA<\/strong> \u2013 ma \u00e8 sempre stata la figura di riferimento per tutti noi, la persona con la quale confrontarsi ogniqualvolta c\u2019era una decisione da prendere o un problema difficile da affrontare\u00bb. E non \u00e8 certo casuale che oggi sia Presidente di SAFIN: omaggio e ringraziamento a una donna che si \u00e8 sempre spesa per il buon andamento sia della famiglia che dell\u2019impresa che aveva contribuito a creare. E pensare che da ragazza, nei suoi piani per il futuro, il matrimonio non era al primo posto, per non parlare della siderurgia, distante mille miglia dai suoi interessi\u2026<br>Ma andiamo con ordine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-62e99f8 e-flex e-con-boxed e-con e-parent\" data-id=\"62e99f8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b5a44a elementor-widget elementor-widget-image\" data-id=\"3b5a44a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9384-Edit.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDE5MTMsInVybCI6Imh0dHBzOlwvXC93d3cuc3R1ZGlvY2hpZXNhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRFNGOTM4NC1FZGl0LmpwZyJ9\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9384-Edit.jpg\" class=\"attachment-large size-large wp-image-41913\" alt=\"\" srcset=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9384-Edit.jpg 1080w, https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9384-Edit-500x333.jpg 500w, https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9384-Edit-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e257017 elementor-widget elementor-widget-text-editor\" data-id=\"e257017\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gino Sangoi nasce a Gemona, territorio friulano sconosciuto ai pi\u00f9 prima dei due devastanti sismi che nel 1976 provocheranno, a distanza di pochi mesi l\u2019uno dall\u2019altro, pi\u00f9 di mille morti e la quasi totale distruzione del tessuto urbano della zona. I genitori hanno un bar che funge anche da rivendita di generi vari in cui Gino, come non era raro ai tempi, inizia a lavorare da bambino: un\u2019infanzia \u00abscippata\u00bb in nome del bilancio famigliare da far quadrare, \u00abe infatti con noi non ne voleva nemmeno parlare\u00bb dice Alessandra. Al bar si affianca presto, nei fine settimana, un lavoro presso una trafileria da poco aperta in paese. La famiglia proprietaria, i Pittini, sar\u00e0 per Gino la scoperta di un modello parentale molto diverso rispetto al suo: \u00abLi ammirava \u2013 racconta Alessandra \u2013 gli piaceva l\u2019ordine che regnava da loro\u00bb, un contesto dove si festeggiavano i Natali e le Pasque che invece a lui erano negati a causa dell\u2019attivit\u00e0 dei genitori. Da l\u00ec nascer\u00e0 il forte desiderio di sposarsi presto, di avere una famiglia tutta sua\u2026 ma come fare per sostenerla economicamente?<br \/>Dai Pittini Gino smonta residuati bellici e carri ferroviari e impara a \u00abmettere le mani\u00bb nel metallo, l\u2019inizio di una passione che durer\u00e0 per tutta la vita nonch\u00e9 risposta alla domanda di cui sopra. A 18 anni comincia nel cortile di casa un\u2019attivit\u00e0 di compravendita di rottami di ferro, poi sviluppa un progetto di realizzazione di carri destinati all\u2019agricoltura utilizzando come ruote gli pneumatici delle auto (\u00absembra avesse riscontrato anche un certo successo commerciale, in ogni caso gli ha fatto assaporare la soddisfazione di assecondare il proprio spirito di iniziativa\u00bb sottolinea Alessandra), infine con un socio apre alla periferia di Udine una rivendita di pezzi di ricambio automobilistici. L\u00ec, quasi di fronte, abita Lidia, una bella ragazza, anche lei con un\u2019infanzia alle spalle segnata dalla sofferenza: il padre partito per la campagna di Russia quando lei aveva solo 4 anni e mai pi\u00f9 tornato, dissolto nel vero senso del termine, come altri 75.000 suoi commilitoni, nella terribile ritirata del gennaio del 1943. Cresciuta in questa grande \u00abassenza\u00bb, tra la madre e il collegio, Lidia sviluppa una personalit\u00e0 forte unita a un desiderio di indipendenza altrettanto robusto. Quando Gino la nota e comincia a frequentarla, sta coltivando il progetto di aprire una sartoria, ha fatto scuola di taglio e cucito a Udine, vuole avere un\u2019attivit\u00e0 sua. Una cosa \u00e8 certa: il matrimonio non \u00e8 nei suoi pensieri.<\/p><p>Ma lo \u00e8 in quelli di Gino. Non \u00e8 tipo da perdere tempo, Lidia per lui \u00e8 la scelta giusta, ne \u00e8 sicuro, e poi \u2013 ma questo non sminuisce la tensione romantica verso la donna di cui \u00e8 innamorato \u2013 vuole a tutti i costi evitare il servizio militare e sposarsi potrebbe essere la soluzione. Cos\u00ec sar\u00e0: non sappiamo come Gino sia riuscito a far capitolare la caparbia Lidia, ma in una foto del 1960 i due sorridono felici dal finestrino di un\u2019auto, lei in abito bianco e velo, lui in scuro.<br \/>Da quel momento tutto accelera: Gino lascia il socio e con Lidia chiede un prestito alla banca per far partire un\u2019attivit\u00e0 di compravendita di materiali ferrosi: ogni settimana va nel Bresciano, dove ormai \u00e8 di casa tra le ferriere, e l\u00ec tratta partite che poi rivende nei laminatoi di Udine. Un avanti-e-indietro massacrante che per\u00f2 d\u00e0 risultati ottimi tant\u2019\u00e8 che a un primo camion se ne aggiunge presto un altro e poco dopo un altro ancora. Il successo commerciale si accompagna alla felicit\u00e0 famigliare: un anno dopo il matrimonio nasce il primogenito Andrea, cui seguir\u00e0 tre anni dopo Paolo e ancora dopo tre anni, Alessandra, la \u00abpiccolina di casa\u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9e5e9b e-flex e-con-boxed e-con e-parent\" data-id=\"e9e5e9b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-095feea elementor-widget elementor-widget-image\" data-id=\"095feea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9378-Edit-.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDE5MTUsInVybCI6Imh0dHBzOlwvXC93d3cuc3R1ZGlvY2hpZXNhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRFNGOTM3OC1FZGl0LS5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9378-Edit-.jpg\" class=\"attachment-large size-large wp-image-41915\" alt=\"\" srcset=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9378-Edit-.jpg 1080w, https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9378-Edit--500x333.jpg 500w, https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9378-Edit--768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-028a53b elementor-widget elementor-widget-text-editor\" data-id=\"028a53b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chi \u00e8 che diceva che gli dei invidiano la felicit\u00e0 umana e quando dai loro scranni dorati la notano, la fanno pagare ai malcapitati? \u00c8 il 1972 quando Gino rischia di morire in un banale incidente di caccia: dal fucile di uno degli amici parte accidentalmente un colpo che lo prende in pieno. Ci metter\u00e0 mesi a riprendersi, ma intanto l\u2019assicurazione paga e quei soldi sono benedetti perch\u00e9 con essi <strong>Gino e Lidia acquistano nel 1973 un terreno a Feletto Umberto e danno il via alla SANGOI SPA, all\u2019inizio, cos\u00ec la descrive Alessandra, \u00abun semplice magazzino di prodotti siderurgici lunghi\u00bb.<\/strong> Chiss\u00e0 se sar\u00e0 sempre stata opera degli dei invidiosi il terremoto che dopo soli tre anni squassa il Friuli\u2026 Il capannone non ne risente, ma la casa che Gino aveva appena acquistato a Tarcento e dove tutta la famiglia a breve si sarebbe trasferita non esiste praticamente pi\u00f9. E nemmeno si pu\u00f2 dire che la fase di ricostruzione sul territorio, che per molte aziende locali fu una grande opportunit\u00e0, abbia impattato in modo benefico su SANGOI: banalmente perch\u00e9 i loro prodotti non erano destinati all\u2019edilizia.<\/p><p>Un passo importante nello sviluppo del Gruppo si localizza temporalmente negli anni Ottanta quando avviene il <strong>passaggio da magazzino di prodotti lunghi a centro servizi<\/strong>: la sede operativa viene trasferita da Feletto a un nuovo capannone in Tarcento, inizialmente con due piccole macchine destinate al taglio longitudinale di nastri in acciaio acquistate da un\u2019azienda in difficolt\u00e0. Un ruolo fondamentale in questa svolta dal commercio all\u2019industria \u00e8 ricoperto da Andrea, il primogenito, che nel frattempo ha terminato gli studi di ragioneria ed \u00e8 entrato nell\u2019attivit\u00e0 famigliare: lui sta guardando pi\u00f9 lontano del padre ma questi, forse per la prima volta nella sua vita, esita di fronte alle prime inevitabili difficolt\u00e0 del nuovo corso imprenditoriale. La storia famigliare narra che sar\u00e0 Lidia a convincerlo a non arrendersi: i debiti saranno pagati vendendo alcune propriet\u00e0, si andr\u00e0 avanti sulla nuova strada. E sar\u00e0 sempre Andrea a rendersi conto che in Lombardia le opportunit\u00e0 sono maggiori ma che dal Friuli \u00e8 difficile gestire la logistica: propone cos\u00ec <strong>l\u2019acquisto, nel 2000, della Unisider di Paderno Dugnano, impresa in crisi per problemi di passaggio generazionale, che diventer\u00e0 la SIDECO.<\/strong><\/p><p>Nel frattempo \u00e8 entrata in scena Alessandra. Il suo rapporto con il padre \u00e8 strettissimo, un\u2019intesa profonda, immediata: \u00abci bastava uno sguardo per capire cosa stava pensando l\u2019altro rispetto a qualsiasi contingenza. E c\u2019\u00e8 sempre stata molta sintonia, avevamo le stesse visioni, ci ritrovavamo sempre in un dialogo che \u00e8 stato molto pi\u00f9 semplice rispetto a quello che lui aveva con i miei fratelli, forse perch\u00e9 la sua personalit\u00e0 era\u2026 molto ingombrante, per cos\u00ec dire, e con i figli maschi era normale che si scontrasse di pi\u00f9\u00bb. Ci\u00f2 nonostante Alessandra non si \u00e8 mai sentita predestinata a una carriera in SANGOI: \u00abal contrario, avevo moltissimi dubbi anche se, dopo la laurea in Economia Aziendale, sono comunque entrata in azienda per capire cosa davvero volessi fare. Niente di che, per lo pi\u00f9 ruoli impiegatizi occupandomi un po\u2019 di tutto. In quegli anni viaggiavo molto con mio padre, lui si occupava in particolare dell\u2019investimento in macchinari, gli piaceva acquistare quelli usati, sistemarli e poi destinarli alle nostre attivit\u00e0 produttive oppure rivenderli e io lo accompagnavo. A dire la verit\u00e0 anche da bambina mi portava per ferriere e acciaierie, ma nel periodo che io chiamo \u201cdella mia indecisione\u201d mi sono resa conto che lo faceva in modo diverso, mi spiegava tanti dettagli tecnici riguardanti le macchine e capivo che quei momenti lo appagavano molto\u00bb.<\/p><p>Gino in realt\u00e0 ha gi\u00e0 in mente un piano per la figlia. <strong>Nel 1997 a un\u2019asta giudiziaria ha acquistato un capannone non lontano dalla SANGOI e ci ha installato due profilatrici per la produzione di tubi saldati di piccolo diametro, da destinare al settore dei giocattoli e dei lampadari: il progetto \u00e8 di nicchia, ma interessante<\/strong>. Peccato che il prodotto non sia all\u2019altezza delle sue aspettative, bisogna ripensarlo a partire dall\u2019aumento del diametro dei tubi spostandone cos\u00ec la destinazione al campo dell\u2019arredo dove per\u00f2 la concorrenza \u00e8 assai pi\u00f9 spinta. Il gioco si fa duro e <strong>Gino gli mette a capo proprio Alessandra<\/strong>: \u00ab\u00e8 stata un\u2019impresa davvero impegnativa \u2013 ricorda \u2013 perch\u00e9 sono entrata in una tempesta perfetta, un concentrato di inadeguatezze che nemmeno progettandolo a tavolino sarebbe risultato cos\u00ec negativamente perfetto: i macchinari non funzionavano, i dipendenti non si trovavano e alcuni stretti collaboratori erano inaffidabili\u00bb. Ma Alessandra riesce a tenere brillantemente il timone, tanto che quando si presenter\u00e0 l\u2019occasione di cedere questo ramo d\u2019azienda a un gruppo leader nella produzione di quei tubi, la Profilmec, la nuova propriet\u00e0 le chiede di restare come amministratore unico. Porter\u00e0 avanti l\u2019esperienza, da lei definita \u00abmolto formativa\u00bb fino al 2007, vero <em>annus horribilis<\/em> per la famiglia Sangoi.<br \/>Nell\u2019estate di quell\u2019anno viene infatti improvvisamente a mancare Gino e dopo tre anni Andrea: per Alessandra \u00e8 il giro di boa, deve e vuole rientrare nell\u2019impresa famigliare anche per \u00abdare un seguito allo spirito di intraprendenza che sia mio padre che mio fratello avevano dimostrato. Ero fiera di raccoglierne il testimone\u00bb. In azienda non resta sola: la affiancano l\u2019altro fratello Paolo e la moglie di Andrea, ma il momento \u00e8 difficile, inevitabile che sorga anche l\u2019idea di vendere. Sar\u00e0 ancora Lidia a spronarli, a farsi interprete di una resilienza veramente friulana. I tre mettono a punto un piano di diversificazione dell\u2019attivit\u00e0 storica che permetter\u00e0 di superare anche la crisi economica iniziata nel 2008 con drammatiche chiusure per tante imprese del nostro Paese.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cc14ca8 e-flex e-con-boxed e-con e-parent\" data-id=\"cc14ca8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95308fc elementor-widget elementor-widget-image\" data-id=\"95308fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF2123-Edit.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDE5MTcsInVybCI6Imh0dHBzOlwvXC93d3cuc3R1ZGlvY2hpZXNhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRFNGMjEyMy1FZGl0LmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF2123-Edit.jpg\" class=\"attachment-large size-large wp-image-41917\" alt=\"\" srcset=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF2123-Edit.jpg 1080w, https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF2123-Edit-500x333.jpg 500w, https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF2123-Edit-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">La famiglia Sangoi: da sinistra a destra, Edi Bassi moglie di Andrea Sangoi, Paolo Sangoi, Lidia Pino e Alessandra Sangoi.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36cb70e elementor-widget elementor-widget-text-editor\" data-id=\"36cb70e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Con i suoi 100 milioni di fatturato<\/strong> oggi il gruppo SANGOI \u00e8 la dimostrazione che in quel frangente la famiglia aveva preso la giusta decisione. Alessandra \u00e8 onesta quando specifica che il brillante risultato ha al suo interno una componente legata alla dinamica dei prezzi dell\u2019acciaio, ma molto decisa nell\u2019intenzione di attestarsi su questi valori anche se i prezzi dovessero arretrare. In pi\u00f9 nell\u2019immediato futuro dell\u2019impresa c\u2019\u00e8 una diversificazione incentrata sul fotovoltaico, anzi si sta gi\u00e0 costruendo un primo parco su terreni di propriet\u00e0. Altri numeri? Quattro sedi operative di cui due a Tarcento, una a Brescia e una a Paderno Dugnano, altri due capannoni locati a terzi, 90 dipendenti e una superficie coperta che si aggira sui 30.000 metri quadrati.<br \/><strong>Un\u2019impresa solida, dichiaratamente fondata su valori oggi quasi fuori moda<\/strong>: la lealt\u00e0, la trasparenza, il senso di responsabilit\u00e0, l\u2019umilt\u00e0: \u00abriflettono la storia della nostra famiglia, il modo in cui i nostri genitori hanno avviato l\u2019attivit\u00e0 partendo quasi dal nulla non solo dal punto di vista dei mezzi economici, ma anche da quello del <em>know how<\/em> come si direbbe oggi. Con il solo bagaglio di questa consapevolezza hanno avuto la capacit\u00e0 e prima ancora la volont\u00e0 di formarsi, di crearsi una reputazione e di dimostrarsi all\u2019altezza della fiducia degli altri\u00bb.<\/p><p>Alessandra \u00e8 una manager che definirei \u00abgarbata\u00bb a partire dalla pacata gentilezza che traspare dalle sue parole e dai suoi modi. \u00c8 il suo stile di <em>management<\/em>: \u00abCredo che riconoscimento e autorevolezza si ottengano sia dimostrando di saper risolvere le criticit\u00e0 sia approcciando la quotidianit\u00e0 in modo equilibrato. Non \u00e8 sempre facile perch\u00e9 i problemi ci sono, mettono ansia e invece bisogna trasferire ai collaboratori tranquillit\u00e0 e rassicurazione\u00bb. <strong><em>Team<\/em> per lei \u00e8 la parola chiave<\/strong>, rispecchia un piacere non solo di lavorare con gli altri in vista di determinati obiettivi, ma anche di \u00abstare\u00bb con le persone: \u00ab\u00c8 solo se stai bene con chi ti circonda, solo se ti piace, che riesci a trascinarlo\u00bb.<br \/>L\u2019essere donna in un settore cos\u00ec maschile per lei non \u00e8 mai stato un problema anche se \u00e8 consapevole dell\u2019esistenza di una certa diffidenza iniziale che bisogna dissipare dimostrando di essere all\u2019altezza. E d\u2019altra parte \u00abnessuno si sorprende pi\u00f9 di trovare una donna al vertice, e non solo nella conduzione di aziende, ma in tanti altri ambiti\u00bb. <strong>Ritiene il mondo dell\u2019acciaio stimolante per tanti motivi<\/strong>, \u00abda un punto di vista tecnologico, e poi per le forze in gioco e le energie, sia fisiche sia finanziarie, necessarie a gestirle\u00bb, ma sa che pu\u00f2 risultare poco affascinante per la sensibilit\u00e0 femminile. In ogni caso, racconta, \u00e8 capitato che donne entrate in SANGOI per ricoprire certi ruoli abbiano poi finito per occuparsi di altri pi\u00f9 prettamente maschili dimostrando peraltro di cavarsela anche meglio. Perch\u00e9? Alessandra sorride: \u00abNella nostra attivit\u00e0 i ritmi sono veloci, devi essere mentalmente reattivo. E questa reattivit\u00e0 l\u2019ho forse riscontrata, anche se non voglio generalizzare, pi\u00f9 nelle donne che negli uomini\u00bb. Un\u2019altra sua convinzione \u00e8 che le donne abbiano una visione pi\u00f9 corretta delle varie situazioni per la loro capacit\u00e0 di osservare le cose con maggior distacco, senza l\u2019ansia di voler primeggiare a tutti i costi.<\/p><p>Anche in SANGOI, come per tante altre imprese del nostro Paese, <strong>un tema cruciale \u00e8 l\u2019attrazione dei talenti e naturalmente la capacit\u00e0 di trattenerli,<\/strong> in un settore in cui l\u2019offerta sta nettamente superando la domanda e dove quindi non \u00e8 difficile spostarsi da una realt\u00e0 a un\u2019altra. Per Alessandra, la strumento principale passa per i valori del Gruppo, che sono stati individuati e condivisi con tutte le aziende che ne fanno parte in un percorso sulle tematiche ESG iniziato nel 2023. Valori su cui bisogna poi mostrarsi tutti coesi e coerenti \u2013 \u00abnon basta enunciarli, bisogna che ciascuno li faccia propri\u00bb \u2013 e che \u2013 lei ne \u00e8 convinta \u2013 creano <strong>un clima positivo all\u2019interno dell\u2019azienda, uno spirito di comunit\u00e0 inclusivo e rispettoso, tale da indurre ad approcciarsi a SANGOI e poi a restarvi<\/strong>. Nessuna demonizzazione dell\u2019atteggiamento che oggi i giovani hanno nei confronti del lavoro e che \u00e8 molto diverso da quello delle generazioni pi\u00f9 <em>ag\u00e9e<\/em>: \u00abbisogna essere consapevoli che la tendenza non \u00e8 pi\u00f9 quella di legarsi indissolubilmente a un\u2019azienda perch\u00e9 il lavoro non viene considerato, come forse un tempo era, l\u2019aspetto pi\u00f9 importante della vita. Bisogna fornire delle motivazioni per cui valga la pena di restare: la retribuzione certo \u00e8 importante, ma un peso rilevante l\u2019ha anche l\u2019ambiente che deve essere aperto e stimolante\u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4830998 e-flex e-con-boxed e-con e-parent\" data-id=\"4830998\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01e7bc6 elementor-widget elementor-widget-image\" data-id=\"01e7bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9347-Edit.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDE5MTksInVybCI6Imh0dHBzOlwvXC93d3cuc3R1ZGlvY2hpZXNhLml0XC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wM1wvRFNGOTM0Ny1FZGl0LmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9347-Edit.jpg\" class=\"attachment-large size-large wp-image-41919\" alt=\"\" srcset=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9347-Edit.jpg 1080w, https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9347-Edit-500x333.jpg 500w, https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/DSF9347-Edit-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8453ec8 elementor-widget elementor-widget-text-editor\" data-id=\"8453ec8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E gli stimoli qui non mancano. Perch\u00e9 <strong>un\u2019altra parola basilare per Alessandra \u00e8 innovazione<\/strong>. Non solo per quanto riguarda le attivit\u00e0 e gli impianti (della svolta nel fotovoltaico abbiamo gi\u00e0 parlato), ma anche nell\u2019organizzazione e nell\u2019approccio al mercato: \u00abNon devi mai sentirti \u201carrivato\u201d, al contrario devi sempre identificare ambiti di miglioramento il che implica un\u2019osservazione costante dei cambiamenti in atto. Non solo, ma poich\u00e9 tutti devono viaggiare alla stessa velocit\u00e0, l\u2019innovazione comporta anche <strong>un\u2019adeguata e continua formazione dei collaboratori<\/strong> perch\u00e9 altrimenti non ti seguono e le idee finiscono per restare tali\u00bb. Alessandra ammette che possa risultare stancante, soprattutto se una persona ambisce alla stabilit\u00e0: qui bisogna rimettere sempre tutto in discussione, ma questa tensione \u00e8 quella che muove l\u2019azienda e \u00abio stessa \u2013 ride \u2013 una <em>comfort zone<\/em> non l\u2019ho proprio mai avuta\u00bb.<\/p><p>Innovazione anche nella comunicazione: <strong>dal periodo del post Covid, SANGOI mette periodicamente a disposizione dei clienti una serie di informazioni<\/strong> <strong>sull\u2019andamento del mercato<\/strong> che vengono comunicate tramite newsletter e successivamente postate sul sito aziendale. Un\u2019idea di Alessandra: \u00abOrmai non seguo pi\u00f9 di tanto la parte commerciale, ma mi capita talvolta di andare a visitare dei clienti sia per mantenere i rapporti sia per capire come si stanno evolvendo e subito dopo il <em>lockdown<\/em>, un momento in cui i prezzi erano saliti in modo molto forte generando sconcerto e un po\u2019 di ansia, mi ero resa conto che da parte dei nostri interlocutori c\u2019era il bisogno urgente di confrontarsi, di capire come interpretavamo i dati, che sensazioni avevamo sul prossimo futuro, come vedevamo in prospettiva le cose. D\u2019altro canto noi dovevamo e dobbiamo documentarci per poter poi operare le nostre scelte. Da qui \u00e8 nata la decisione di condividere queste informazioni con i nostri clienti, cosa che \u00e8 stata cos\u00ec apprezzata da indurci a continuare\u00bb. La prova del nove della bont\u00e0 dell\u2019iniziativa \u00e8 che alcuni <em>competitor<\/em> l\u2019hanno copiata, pur se in modo pi\u00f9 superficiale. Infatti se SANGOI si impegna in sintesi e rielaborazioni dei dati, gli altri si limitano a indicare delle fonti a cui accedere per trovare le informazioni.<\/p><p>\u00a0Si tratta peraltro di uno strumento connotante dello <strong>spirito \u00abdi servizio\u00bb dell\u2019azienda<\/strong>, prova tangibile della capacit\u00e0 di prestare attenzione a ogni necessit\u00e0 dei clienti. <em>Tailor made<\/em> \u00e8 l\u2019espressione che qui viene usata per definire questo approccio, prima di tutto alla produzione: si va incontro alle esigenze specifiche in modo molto personalizzato. E pazienza se c\u2019\u00e8 un rovescio della medaglia, \u00abrispetto ad altri nostri <em>competitor<\/em>, non siamo quelli che hanno gli impianti pi\u00f9 automatizzati perch\u00e9 sarebbe in contrasto con il nostro modo di lavorare\u00bb. Anche questo \u00e8 un valore di SANGOI.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ci sono frasi nel dire comune che sono specchio stucchevole e, diciamolo, ormai insopportabile, di stereotipi di genere: per esempio certi luoghi comuni allusivi e denigratori delle capacit\u00e0 delle donne in campo lavorativo oppure delle loro abilit\u00e0, per non parlare di quelli che, al contrario, legano l\u2019affermazione femminile nei campi pi\u00f9 vari alla seduttivit\u00e0 o alla bellezza. <\/p>","protected":false},"author":14,"featured_media":41909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[233],"tags":[223],"class_list":["post-41908","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-heritage","tag-223"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ritratto Friulano - Studio Chiesa<\/title>\n<meta name=\"description\" content=\"Un\u2019impresa solida, dichiaratamente fondata su valori oggi quasi fuori moda: la lealt\u00e0, la trasparenza, il senso di responsabilit\u00e0, l\u2019umilt\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.studiochiesa.it\/en\/ritratto-friulano\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ritratto Friulano - Studio Chiesa\" \/>\n<meta property=\"og:description\" content=\"Un\u2019impresa solida, dichiaratamente fondata su valori oggi quasi fuori moda: la lealt\u00e0, la trasparenza, il senso di responsabilit\u00e0, l\u2019umilt\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.studiochiesa.it\/en\/ritratto-friulano\/\" \/>\n<meta property=\"og:site_name\" content=\"Studio Chiesa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Studio-Chiesa\/407194632625821\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-19T09:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-25T14:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Brasca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Brasca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/\"},\"author\":{\"name\":\"Anna Brasca\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#\\\/schema\\\/person\\\/b88881d1831fb372f1b92a66d564d5ca\"},\"headline\":\"Ritratto Friulano\",\"datePublished\":\"2024-03-19T09:00:57+00:00\",\"dateModified\":\"2025-03-25T14:43:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/\"},\"wordCount\":3208,\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.studiochiesa.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg\",\"keywords\":[\"2023\"],\"articleSection\":[\"Heritage\"],\"inLanguage\":\"en-GB\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/\",\"name\":\"Ritratto Friulano - Studio Chiesa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.studiochiesa.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg\",\"datePublished\":\"2024-03-19T09:00:57+00:00\",\"dateModified\":\"2025-03-25T14:43:21+00:00\",\"description\":\"Un\u2019impresa solida, dichiaratamente fondata su valori oggi quasi fuori moda: la lealt\u00e0, la trasparenza, il senso di responsabilit\u00e0, l\u2019umilt\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg\",\"contentUrl\":\"https:\\\/\\\/www.studiochiesa.it\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/ritratto-friulano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.studiochiesa.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ritratto Friulano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/\",\"name\":\"Studio Chiesa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#organization\",\"name\":\"Studio Chiesa Communication\",\"alternateName\":\"Studio Chiesa\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/quadratino_SC.jpg\",\"contentUrl\":\"https:\\\/\\\/www.studiochiesa.it\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/quadratino_SC.jpg\",\"width\":696,\"height\":696,\"caption\":\"Studio Chiesa Communication\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Studio-Chiesa\\\/407194632625821\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/studio-chiesa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/studiochiesa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/StudioChiesa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/#\\\/schema\\\/person\\\/b88881d1831fb372f1b92a66d564d5ca\",\"name\":\"Anna Brasca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0dd1f84ae4721a181705fd5431b9db97a45a6c736eb0e74ffc4e9912c97186a8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0dd1f84ae4721a181705fd5431b9db97a45a6c736eb0e74ffc4e9912c97186a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0dd1f84ae4721a181705fd5431b9db97a45a6c736eb0e74ffc4e9912c97186a8?s=96&d=mm&r=g\",\"caption\":\"Anna Brasca\"},\"description\":\"Da sempre innamorata del mondo della carta stampata, sono stata per diversi anni direttrice editoriale di De Agostini Publishing Italia mentre oggi ho un\u2019agenzia editoriale che mi consente di restare in contatto con libri e pubblicazioni destinati sia agli adulti sia ai kids. Collaboro con Studio Chiesa Communication nell\u2019ambito della cultura d\u2019impresa, un tema che mi ha consentito di scoprire quanta inaspettata bellezza ci sia nell\u2019industria italiana.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/annabrasca\\\/\"],\"url\":\"https:\\\/\\\/www.studiochiesa.it\\\/en\\\/author\\\/anna-brasca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ritratto Friulano - Studio Chiesa","description":"Un\u2019impresa solida, dichiaratamente fondata su valori oggi quasi fuori moda: la lealt\u00e0, la trasparenza, il senso di responsabilit\u00e0, l\u2019umilt\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.studiochiesa.it\/en\/ritratto-friulano\/","og_locale":"en_GB","og_type":"article","og_title":"Ritratto Friulano - Studio Chiesa","og_description":"Un\u2019impresa solida, dichiaratamente fondata su valori oggi quasi fuori moda: la lealt\u00e0, la trasparenza, il senso di responsabilit\u00e0, l\u2019umilt\u00e0.","og_url":"https:\/\/www.studiochiesa.it\/en\/ritratto-friulano\/","og_site_name":"Studio Chiesa","article_publisher":"https:\/\/www.facebook.com\/pages\/Studio-Chiesa\/407194632625821","article_published_time":"2024-03-19T09:00:57+00:00","article_modified_time":"2025-03-25T14:43:21+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg","type":"image\/jpeg"}],"author":"Anna Brasca","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Anna Brasca","Estimated reading time":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/#article","isPartOf":{"@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/"},"author":{"name":"Anna Brasca","@id":"https:\/\/www.studiochiesa.it\/en\/#\/schema\/person\/b88881d1831fb372f1b92a66d564d5ca"},"headline":"Ritratto Friulano","datePublished":"2024-03-19T09:00:57+00:00","dateModified":"2025-03-25T14:43:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/"},"wordCount":3208,"publisher":{"@id":"https:\/\/www.studiochiesa.it\/en\/#organization"},"image":{"@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg","keywords":["2023"],"articleSection":["Heritage"],"inLanguage":"en-GB","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.studiochiesa.it\/en\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/","url":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/","name":"Ritratto Friulano - Studio Chiesa","isPartOf":{"@id":"https:\/\/www.studiochiesa.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/#primaryimage"},"image":{"@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg","datePublished":"2024-03-19T09:00:57+00:00","dateModified":"2025-03-25T14:43:21+00:00","description":"Un\u2019impresa solida, dichiaratamente fondata su valori oggi quasi fuori moda: la lealt\u00e0, la trasparenza, il senso di responsabilit\u00e0, l\u2019umilt\u00e0.","breadcrumb":{"@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.studiochiesa.it\/ritratto-friulano\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/#primaryimage","url":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg","contentUrl":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2024\/03\/2024_03_19_Sangoi_LinkedIn_Facebook.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.studiochiesa.it\/ritratto-friulano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.studiochiesa.it\/"},{"@type":"ListItem","position":2,"name":"Ritratto Friulano"}]},{"@type":"WebSite","@id":"https:\/\/www.studiochiesa.it\/en\/#website","url":"https:\/\/www.studiochiesa.it\/en\/","name":"Studio Chiesa","description":"","publisher":{"@id":"https:\/\/www.studiochiesa.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.studiochiesa.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.studiochiesa.it\/en\/#organization","name":"Studio Chiesa Communication","alternateName":"Studio Chiesa","url":"https:\/\/www.studiochiesa.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.studiochiesa.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2023\/05\/quadratino_SC.jpg","contentUrl":"https:\/\/www.studiochiesa.it\/wp-content\/uploads\/2023\/05\/quadratino_SC.jpg","width":696,"height":696,"caption":"Studio Chiesa Communication"},"image":{"@id":"https:\/\/www.studiochiesa.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Studio-Chiesa\/407194632625821","https:\/\/www.linkedin.com\/company\/studio-chiesa\/","https:\/\/www.instagram.com\/studiochiesa\/","https:\/\/www.youtube.com\/user\/StudioChiesa"]},{"@type":"Person","@id":"https:\/\/www.studiochiesa.it\/en\/#\/schema\/person\/b88881d1831fb372f1b92a66d564d5ca","name":"Anna Brasca","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/0dd1f84ae4721a181705fd5431b9db97a45a6c736eb0e74ffc4e9912c97186a8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0dd1f84ae4721a181705fd5431b9db97a45a6c736eb0e74ffc4e9912c97186a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0dd1f84ae4721a181705fd5431b9db97a45a6c736eb0e74ffc4e9912c97186a8?s=96&d=mm&r=g","caption":"Anna Brasca"},"description":"Da sempre innamorata del mondo della carta stampata, sono stata per diversi anni direttrice editoriale di De Agostini Publishing Italia mentre oggi ho un\u2019agenzia editoriale che mi consente di restare in contatto con libri e pubblicazioni destinati sia agli adulti sia ai kids. Collaboro con Studio Chiesa Communication nell\u2019ambito della cultura d\u2019impresa, un tema che mi ha consentito di scoprire quanta inaspettata bellezza ci sia nell\u2019industria italiana.","sameAs":["https:\/\/www.linkedin.com\/in\/annabrasca\/"],"url":"https:\/\/www.studiochiesa.it\/en\/author\/anna-brasca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/posts\/41908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/comments?post=41908"}],"version-history":[{"count":5,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/posts\/41908\/revisions"}],"predecessor-version":[{"id":44398,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/posts\/41908\/revisions\/44398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/media\/41909"}],"wp:attachment":[{"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/media?parent=41908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/categories?post=41908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiochiesa.it\/en\/wp-json\/wp\/v2\/tags?post=41908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}